{"id":8034,"date":"2026-01-19T10:50:19","date_gmt":"2026-01-19T09:50:19","guid":{"rendered":"https:\/\/echt.community\/?p=8034"},"modified":"2026-01-19T10:50:19","modified_gmt":"2026-01-19T09:50:19","slug":"blue-monday-wij-hebben-goed-nieuws","status":"publish","type":"post","link":"https:\/\/echt.community\/en\/blue-monday-wij-hebben-goed-nieuws\/","title":{"rendered":"Blue Monday? Wij hebben goed nieuws!"},"content":{"rendered":"<p>Op Blue Monday is er genoeg om optimistisch over te zijn: de duurzame blauwe economie groeit hard. En die groei brengt Europa banen, innovatie \u00e9n oplossingen voor het klimaat.<\/p>\n\n\n\n<p><strong>Wat is de blauwe economie?<\/strong><br>De duurzame blauwe economie omvat alle economische activiteiten die afhankelijk zijn van onze zee\u00ebn en kusten, binnen de ecologische grenzen van het ecosysteem. In Europa heeft deze economie al een stevige basis \u00e9n een enorme groeiruimte. Het gaat allang niet meer om een niche. Het geeft namelijk:<br>\u2022 honderden miljarden euro\u2019s aan toegevoegde waarde<br>\u2022 miljoenen banen<br>\u2022 een volwaardige, groeiende pijler van onze economie<\/p>\n\n\n\n<p><strong>Waar zit de duurzame groeipotentie?<\/strong><br>De kansen zijn groot en divers:<br><br><em>Offshore hernieuwbare energie<br><\/em>Wind op zee, energienetten en offshore energiehubs als motor voor industrie, havens en werkgelegenheid.<br><br><em>Duurzame aquacultuur &amp; blue bio-economy<\/em><br>Zeewier, schelpdieren en biomassa voor voedsel, materialen en biobased innovatie.<br><br><em>Groene havens &amp; schonere scheepvaart<br><\/em>Elektrificatie, walstroom en nieuwe maritieme diensten.<br><br><em>Kusttoerisme, natuurherstel &amp; klimaatadaptatie<br><\/em>Natuurgebaseerde oplossingen die economie \u00e9n leefomgeving versterken.<\/p>\n\n\n\n<p><strong>Wat is onze rol daarin?<\/strong><br>In Erwin Coolen zijn rol als alliantieco\u00f6rdinator SDG 14 \u2013 Life Below Water ziet hij dagelijks hoe sterke economie en ecologie met elkaar verweven zijn.<br>Zonder gezonde zee geen duurzame groei. Of steeds duidelijker gezegd: No green without blue.<\/p>\n\n\n\n<p><strong>En wat versnelt de blauwe economie dan echt?<\/strong><br>\u2022 Snelle, voorspelbare en natuur-inclusieve ruimtelijke planning<br>\u2022 Investeren in netten, havens en maritieme ketens<br>\u2022 Mensen: technici, maritieme ingenieurs, ecologen en ondernemers<br>\u2022 Herstel van natuur en waterkwaliteit als fundament<br>\u2022 Slim medegebruik van ruimte op zee<br><br>Dus op deze Blue Monday geen somberheid, maar richting en kansen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Op Blue Monday is er genoeg om optimistisch over te zijn: de duurzame blauwe economie groeit hard. En die groei brengt Europa banen, innovatie \u00e9n oplossingen voor het klimaat. Wat is de blauwe economie?De duurzame blauwe economie omvat alle economische activiteiten die afhankelijk zijn van onze zee\u00ebn en kusten, binnen de ecologische grenzen van het ecosysteem. In Europa heeft deze economie al een stevige basis \u00e9n een enorme groeiruimte. Het gaat allang niet meer om een niche. Het geeft namelijk:\u2022 honderden miljarden euro\u2019s aan toegevoegde waarde\u2022 miljoenen banen\u2022 een volwaardige, groeiende pijler van onze economie Waar zit de duurzame groeipotentie?De kansen zijn groot en divers: Offshore hernieuwbare energieWind op zee, energienetten en offshore energiehubs als motor voor industrie, havens en werkgelegenheid. Duurzame aquacultuur &amp; blue bio-economyZeewier, schelpdieren en biomassa voor voedsel, materialen en biobased innovatie. Groene havens &amp; schonere scheepvaartElektrificatie, walstroom en nieuwe maritieme diensten. Kusttoerisme, natuurherstel &amp; klimaatadaptatieNatuurgebaseerde oplossingen die economie \u00e9n leefomgeving versterken. Wat is onze rol daarin?In Erwin Coolen zijn rol als alliantieco\u00f6rdinator SDG 14 \u2013 Life Below Water ziet hij dagelijks hoe sterke economie en ecologie met elkaar verweven zijn.Zonder gezonde zee geen duurzame groei. Of steeds duidelijker gezegd: No green without blue. En wat versnelt de blauwe economie dan echt?\u2022 Snelle, voorspelbare en natuur-inclusieve ruimtelijke planning\u2022 Investeren in netten, havens en maritieme ketens\u2022 Mensen: technici, maritieme ingenieurs, ecologen en ondernemers\u2022 Herstel van natuur en waterkwaliteit als fundament\u2022 Slim medegebruik van ruimte op zee Dus op deze Blue Monday geen somberheid, maar richting en kansen!<\/p>","protected":false},"author":7,"featured_media":8033,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"categories":[23,34],"tags":[],"class_list":["post-8034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-echt-regie-in-transitie","category-nieuws"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Blue Monday? Wij hebben goed nieuws! - ECHT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/echt.community\/en\/blue-monday-wij-hebben-goed-nieuws\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blue Monday? Wij hebben goed nieuws! - ECHT\" \/>\n<meta property=\"og:description\" content=\"Op Blue Monday is er genoeg om optimistisch over te zijn: de duurzame blauwe economie groeit hard. En die groei brengt Europa banen, innovatie \u00e9n oplossingen voor het klimaat. Wat is de blauwe economie?De duurzame blauwe economie omvat alle economische activiteiten die afhankelijk zijn van onze zee\u00ebn en kusten, binnen de ecologische grenzen van het ecosysteem. In Europa heeft deze economie al een stevige basis \u00e9n een enorme groeiruimte. Het gaat allang niet meer om een niche. Het geeft namelijk:\u2022 honderden miljarden euro\u2019s aan toegevoegde waarde\u2022 miljoenen banen\u2022 een volwaardige, groeiende pijler van onze economie Waar zit de duurzame groeipotentie?De kansen zijn groot en divers: Offshore hernieuwbare energieWind op zee, energienetten en offshore energiehubs als motor voor industrie, havens en werkgelegenheid. Duurzame aquacultuur &amp; blue bio-economyZeewier, schelpdieren en biomassa voor voedsel, materialen en biobased innovatie. Groene havens &amp; schonere scheepvaartElektrificatie, walstroom en nieuwe maritieme diensten. Kusttoerisme, natuurherstel &amp; klimaatadaptatieNatuurgebaseerde oplossingen die economie \u00e9n leefomgeving versterken. Wat is onze rol daarin?In Erwin Coolen zijn rol als alliantieco\u00f6rdinator SDG 14 \u2013 Life Below Water ziet hij dagelijks hoe sterke economie en ecologie met elkaar verweven zijn.Zonder gezonde zee geen duurzame groei. Of steeds duidelijker gezegd: No green without blue. En wat versnelt de blauwe economie dan echt?\u2022 Snelle, voorspelbare en natuur-inclusieve ruimtelijke planning\u2022 Investeren in netten, havens en maritieme ketens\u2022 Mensen: technici, maritieme ingenieurs, ecologen en ondernemers\u2022 Herstel van natuur en waterkwaliteit als fundament\u2022 Slim medegebruik van ruimte op zee Dus op deze Blue Monday geen somberheid, maar richting en kansen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/echt.community\/en\/blue-monday-wij-hebben-goed-nieuws\/\" \/>\n<meta property=\"og:site_name\" content=\"ECHT\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-19T09:50:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/echt.community\/wp-content\/uploads\/2026\/01\/Blue-Economy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michelle Peeters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michelle Peeters\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/\"},\"author\":{\"name\":\"Michelle Peeters\",\"@id\":\"https:\/\/echt.community\/#\/schema\/person\/09732f2b3658fa9451d915574c415ab9\"},\"headline\":\"Blue Monday? Wij hebben goed nieuws!\",\"datePublished\":\"2026-01-19T09:50:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/\"},\"wordCount\":264,\"publisher\":{\"@id\":\"https:\/\/echt.community\/#organization\"},\"image\":{\"@id\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/echt.community\/wp-content\/uploads\/2026\/01\/Blue-Economy.jpg\",\"articleSection\":[\"ECHT Regie in transitie\",\"Nieuws\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/\",\"url\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/\",\"name\":\"Blue Monday? Wij hebben goed nieuws! - ECHT\",\"isPartOf\":{\"@id\":\"https:\/\/echt.community\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/echt.community\/wp-content\/uploads\/2026\/01\/Blue-Economy.jpg\",\"datePublished\":\"2026-01-19T09:50:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#primaryimage\",\"url\":\"https:\/\/echt.community\/wp-content\/uploads\/2026\/01\/Blue-Economy.jpg\",\"contentUrl\":\"https:\/\/echt.community\/wp-content\/uploads\/2026\/01\/Blue-Economy.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/echt.community\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blue Monday? Wij hebben goed nieuws!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/echt.community\/#website\",\"url\":\"https:\/\/echt.community\/\",\"name\":\"ECHT\",\"description\":\"Groene en duurzame economie\",\"publisher\":{\"@id\":\"https:\/\/echt.community\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/echt.community\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/echt.community\/#organization\",\"name\":\"ECHT\",\"url\":\"https:\/\/echt.community\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/echt.community\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/echt.community\/wp-content\/uploads\/2024\/04\/ECHT-Group-logo.png\",\"contentUrl\":\"https:\/\/echt.community\/wp-content\/uploads\/2024\/04\/ECHT-Group-logo.png\",\"width\":2498,\"height\":1018,\"caption\":\"ECHT\"},\"image\":{\"@id\":\"https:\/\/echt.community\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/echt.community\/#\/schema\/person\/09732f2b3658fa9451d915574c415ab9\",\"name\":\"Michelle Peeters\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/echt.community\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e3b8d111c1243780d41c49cc62e5f06f0596496cd6769bbf4d6c7fe6d5614114?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e3b8d111c1243780d41c49cc62e5f06f0596496cd6769bbf4d6c7fe6d5614114?s=96&d=mm&r=g\",\"caption\":\"Michelle Peeters\"},\"url\":\"https:\/\/echt.community\/en\/author\/michelle-peeters\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blue Monday? Wij hebben goed nieuws! - ECHT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/echt.community\/en\/blue-monday-wij-hebben-goed-nieuws\/","og_locale":"en_GB","og_type":"article","og_title":"Blue Monday? Wij hebben goed nieuws! - ECHT","og_description":"Op Blue Monday is er genoeg om optimistisch over te zijn: de duurzame blauwe economie groeit hard. En die groei brengt Europa banen, innovatie \u00e9n oplossingen voor het klimaat. Wat is de blauwe economie?De duurzame blauwe economie omvat alle economische activiteiten die afhankelijk zijn van onze zee\u00ebn en kusten, binnen de ecologische grenzen van het ecosysteem. In Europa heeft deze economie al een stevige basis \u00e9n een enorme groeiruimte. Het gaat allang niet meer om een niche. Het geeft namelijk:\u2022 honderden miljarden euro\u2019s aan toegevoegde waarde\u2022 miljoenen banen\u2022 een volwaardige, groeiende pijler van onze economie Waar zit de duurzame groeipotentie?De kansen zijn groot en divers: Offshore hernieuwbare energieWind op zee, energienetten en offshore energiehubs als motor voor industrie, havens en werkgelegenheid. Duurzame aquacultuur &amp; blue bio-economyZeewier, schelpdieren en biomassa voor voedsel, materialen en biobased innovatie. Groene havens &amp; schonere scheepvaartElektrificatie, walstroom en nieuwe maritieme diensten. Kusttoerisme, natuurherstel &amp; klimaatadaptatieNatuurgebaseerde oplossingen die economie \u00e9n leefomgeving versterken. Wat is onze rol daarin?In Erwin Coolen zijn rol als alliantieco\u00f6rdinator SDG 14 \u2013 Life Below Water ziet hij dagelijks hoe sterke economie en ecologie met elkaar verweven zijn.Zonder gezonde zee geen duurzame groei. Of steeds duidelijker gezegd: No green without blue. En wat versnelt de blauwe economie dan echt?\u2022 Snelle, voorspelbare en natuur-inclusieve ruimtelijke planning\u2022 Investeren in netten, havens en maritieme ketens\u2022 Mensen: technici, maritieme ingenieurs, ecologen en ondernemers\u2022 Herstel van natuur en waterkwaliteit als fundament\u2022 Slim medegebruik van ruimte op zee Dus op deze Blue Monday geen somberheid, maar richting en kansen!","og_url":"https:\/\/echt.community\/en\/blue-monday-wij-hebben-goed-nieuws\/","og_site_name":"ECHT","article_published_time":"2026-01-19T09:50:19+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/echt.community\/wp-content\/uploads\/2026\/01\/Blue-Economy.jpg","type":"image\/jpeg"}],"author":"Michelle Peeters","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Michelle Peeters","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#article","isPartOf":{"@id":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/"},"author":{"name":"Michelle Peeters","@id":"https:\/\/echt.community\/#\/schema\/person\/09732f2b3658fa9451d915574c415ab9"},"headline":"Blue Monday? Wij hebben goed nieuws!","datePublished":"2026-01-19T09:50:19+00:00","mainEntityOfPage":{"@id":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/"},"wordCount":264,"publisher":{"@id":"https:\/\/echt.community\/#organization"},"image":{"@id":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#primaryimage"},"thumbnailUrl":"https:\/\/echt.community\/wp-content\/uploads\/2026\/01\/Blue-Economy.jpg","articleSection":["ECHT Regie in transitie","Nieuws"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/","url":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/","name":"Blue Monday? Wij hebben goed nieuws! - ECHT","isPartOf":{"@id":"https:\/\/echt.community\/#website"},"primaryImageOfPage":{"@id":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#primaryimage"},"image":{"@id":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#primaryimage"},"thumbnailUrl":"https:\/\/echt.community\/wp-content\/uploads\/2026\/01\/Blue-Economy.jpg","datePublished":"2026-01-19T09:50:19+00:00","breadcrumb":{"@id":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#primaryimage","url":"https:\/\/echt.community\/wp-content\/uploads\/2026\/01\/Blue-Economy.jpg","contentUrl":"https:\/\/echt.community\/wp-content\/uploads\/2026\/01\/Blue-Economy.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/echt.community\/blue-monday-wij-hebben-goed-nieuws\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/echt.community\/"},{"@type":"ListItem","position":2,"name":"Blue Monday? Wij hebben goed nieuws!"}]},{"@type":"WebSite","@id":"https:\/\/echt.community\/#website","url":"https:\/\/echt.community\/","name":"ECHT","description":"Groene en duurzame economie","publisher":{"@id":"https:\/\/echt.community\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/echt.community\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/echt.community\/#organization","name":"ECHT","url":"https:\/\/echt.community\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/echt.community\/#\/schema\/logo\/image\/","url":"https:\/\/echt.community\/wp-content\/uploads\/2024\/04\/ECHT-Group-logo.png","contentUrl":"https:\/\/echt.community\/wp-content\/uploads\/2024\/04\/ECHT-Group-logo.png","width":2498,"height":1018,"caption":"ECHT"},"image":{"@id":"https:\/\/echt.community\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/echt.community\/#\/schema\/person\/09732f2b3658fa9451d915574c415ab9","name":"Michelle Peeters","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/echt.community\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e3b8d111c1243780d41c49cc62e5f06f0596496cd6769bbf4d6c7fe6d5614114?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3b8d111c1243780d41c49cc62e5f06f0596496cd6769bbf4d6c7fe6d5614114?s=96&d=mm&r=g","caption":"Michelle Peeters"},"url":"https:\/\/echt.community\/en\/author\/michelle-peeters\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/posts\/8034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/comments?post=8034"}],"version-history":[{"count":8,"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/posts\/8034\/revisions"}],"predecessor-version":[{"id":8047,"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/posts\/8034\/revisions\/8047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/media\/8033"}],"wp:attachment":[{"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/media?parent=8034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/categories?post=8034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/echt.community\/en\/wp-json\/wp\/v2\/tags?post=8034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}